{"id":711,"date":"2022-12-14T20:42:37","date_gmt":"2022-12-14T20:42:37","guid":{"rendered":"https:\/\/www.dvpb-bayern.de\/?p=711"},"modified":"2025-04-02T13:07:32","modified_gmt":"2025-04-02T13:07:32","slug":"ein-halbjahr-bester-politischer-bildung","status":"publish","type":"post","link":"https:\/\/www.dvpb-bayern.de\/index.php\/2022\/12\/14\/ein-halbjahr-bester-politischer-bildung\/","title":{"rendered":"Ein Halbjahr bester politischer Bildung"},"content":{"rendered":"<p>Auf die Top-Themen Digitalisierung, Klimawandel und Nachhaltigkeit sowie Internationale Politik setzt die <a href=\"https:\/\/www.apb-tutzing.de\/\" target=\"_blank\" rel=\"noopener\">Akademie f\u00fcr Politische Bildung in Tutzing<\/a> mit <a href=\"https:\/\/www.apb-tutzing.de\/programm\/\" target=\"_blank\" rel=\"noopener\">ihrem Programm f\u00fcr die erste Jahresh\u00e4lfte 2023<\/a>. Geplant sind rund 70 Veranstaltungen von Januar bis Juni. Einen Schwerpunkt bildet der Themenkomplex Digitalisierung. Unter anderem besch\u00e4ftigt sich die Akademie mit <em>Smart Governance<\/em> (14.-15.04.) und den notwendigen Updates f\u00fcr die \u00f6ffentliche Verwaltung, mit <em>Algorithmen, Big Data, K\u00fcnstlicher Intelligenz<\/em> (28.-29.04.) und ihren Auswirkungen auf die Lebenswirklichkeit sowie mit automatisiertem Lernen und K\u00fcnstlicher Intelligenz im Bildungssystem (31.01.-01.02.). Die kostenlose Online-Veranstaltungsreihe &#8222;Demokratie im Gespr\u00e4ch&#8220; mit der Bayerischen Landeszentrale f\u00fcr politische Bildungsarbeit und dem Bayerischen Volkshochschulverband e.V. zu verschiedenen Aspekten der Digitalisierung geht 2023 ebenfalls weiter.<\/p>\n<p>Weitere Top-Themen des neuen Programms der Akademie f\u00fcr Politische Bildung sind Internationale Politik sowie Klimawandel und Nachhaltigkeit. Geplant sind Veranstaltungen zu St\u00e4dten und Gemeinden im Klimawandel (15.05.), Klimagerechtigkeit (12.-13.05.) sowie <em>Bauen und Gesellschaft in der \u00f6kologischen Transformation<\/em> (21.-22.04.). Im Bereich der Internationalen Politik und Sicherheitspolitik organisiert die Akademie im ersten Halbjahr 2023 unter anderem Veranstaltungen zu Taiwan (10.01.), ungel\u00f6sten Regionalkonflikten (17.-18.03.) und T\u00fcrkei\/Osteuropa (02.-04.06.). Im Bereich Medien und politische Kommunikation steht unter anderem eine Ideenwerkstatt zur Zukunft des \u00f6ffentlich-rechtlichen Rundfunks (30.05.-01.06.) auf dem Programm, zudem die 20. Tutzinger Radiotage (15.-17.05.). Weitere Themenfelder: Der Fachkr\u00e4ftemangel, Wahlsysteme, Europarecht, Staat und Kirche und vieles, vieles mehr. Besuche in der Akademie am Starnberger See lohnen sich wahrlich immer.<\/p>\n<p><a href=\"https:\/\/www.apb-tutzing.de\/programm\/\" target=\"_blank\" rel=\"noopener\">Zum aktuellen Programm der Akademie f\u00fcr Politische Bildung samt Buchungsm\u00f6glichkeit<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Digitalisierung, Klimawandel, Nachhaltigkeit und Internationale Politik bestimmen in der Akademie f\u00fcr Politische Bildung in Tutzing die Zeit bis Sommer 2023.<\/p>\n","protected":false},"author":2,"featured_media":712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[123],"tags":[77,75,79,76,78],"class_list":["post-711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiv-aktuelles","tag-akademie","tag-politische-bildung","tag-programm","tag-tutzing","tag-veranstaltungen"],"_links":{"self":[{"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/posts\/711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/comments?post=711"}],"version-history":[{"count":3,"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/posts\/711\/revisions"}],"predecessor-version":[{"id":715,"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/posts\/711\/revisions\/715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/media\/712"}],"wp:attachment":[{"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/media?parent=711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/categories?post=711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dvpb-bayern.de\/index.php\/wp-json\/wp\/v2\/tags?post=711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}